{"id":3028,"date":"2023-11-30T17:57:30","date_gmt":"2023-11-30T09:57:30","guid":{"rendered":"https:\/\/plasticrecyclingmachinery.com\/?p=3028"},"modified":"2025-01-14T14:56:30","modified_gmt":"2025-01-14T06:56:30","slug":"plastic-foam-extruder-common-faults","status":"publish","type":"post","link":"https:\/\/plasticrecyclingmachinery.com\/es\/plastic-foam-extruder-common-faults\/","title":{"rendered":"Fallas y soluciones comunes de la extrusora de espuma pl\u00e1stica"},"content":{"rendered":"<p class=\"wp-block-paragraph\">La extrusora de espuma pl\u00e1stica es un equipo com\u00fanmente utilizado para fabricar gr\u00e1nulos de espuma a partir de espuma pl\u00e1stica mediante fusi\u00f3n y extrusi\u00f3n. Sin embargo, en el proceso de uso, pueden ocurrir varias fallas que afectan la eficiencia de la producci\u00f3n. A continuaci\u00f3n se presentar\u00e1n varias fallas comunes y las soluciones correspondientes.<\/p>    <h2 class=\"wp-block-heading\">Calidad desigual del pellet reciclado<\/h2>    <p class=\"wp-block-paragraph\">Las part\u00edculas de espuma reciclada tienen diferentes tama\u00f1os y densidades desiguales durante el proceso de producci\u00f3n, lo que afecta la calidad del producto.<\/p>    <h3 class=\"wp-block-heading\">Soluciones<\/h3>    <ul class=\"wp-block-list\"> <li>Verifique las materias primas: aseg\u00farese de que la calidad y proporci\u00f3n de las materias primas sean correctas y evite mezclar diferentes materiales, lo que resultar\u00e1 en una calidad desigual de los pellets.<\/li>    <li>Ajuste la temperatura y la presi\u00f3n: ajuste la temperatura y la presi\u00f3n del extrusor de espuma pl\u00e1stica de manera adecuada para garantizar que el material de espuma est\u00e9 completamente derretido y distribuido uniformemente.<\/li>    <li>Limpiar los moldes y equipos: Limpiar la superficie de los moldes y <a href=\"https:\/\/plasticrecyclingmachinery.com\/es\/eps-granulator-eps-pelletizer\/\" data-type=\"post\" data-id=\"2447\">extrusora de espuma pl\u00e1stica<\/a> para evitar que los residuos afecten la forma y calidad de los gr\u00e1nulos.<\/li> <\/ul>   <div class=\"wp-block-image\"> <figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/11\/EPS-pelletizing-machine.webp\" alt=\"M\u00e1quina granuladora de EPS\" class=\"wp-image-3013\" srcset=\"https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/11\/EPS-pelletizing-machine.webp 720w, https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/11\/EPS-pelletizing-machine-360x270.webp 360w, https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/11\/EPS-pelletizing-machine-240x180.webp 240w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">M\u00e1quina granuladora de EPS<\/figcaption><\/figure> <\/div>   <h2 class=\"wp-block-heading\">Obstrucci\u00f3n de la extrusora de espuma pl\u00e1stica<\/h2>    <p class=\"wp-block-paragraph\">La espuma pl\u00e1stica extruida puede obstruirse con tuber\u00edas o puertos de alimentaci\u00f3n, lo que provoca la interrupci\u00f3n de la producci\u00f3n.<\/p>    <h3 class=\"wp-block-heading\">Soluciones<\/h3>    <ul class=\"wp-block-list\"> <li>Detener y verificar: Verifique las tuber\u00edas y la entrada de alimentaci\u00f3n a tiempo para eliminar la obstrucci\u00f3n en la condici\u00f3n de parada.<\/li>    <li>Utilice materias primas adecuadas: evite utilizar materias primas demasiado grandes o demasiado peque\u00f1as para evitar obstrucciones.<\/li>    <li>Mantenimiento regular: limpie y mantenga la espuma pl\u00e1stica extruida con regularidad para evitar obstrucciones.<\/li> <\/ul>    <h2 class=\"wp-block-heading\">Anomal\u00eda en el ruido del granulador de espuma<\/h2>    <p class=\"wp-block-paragraph translation-block\">La <a href=\"https:\/\/plasticrecyclingmachinery.com\/es\/epe-foam-pelletizing-machine\/\" data-type=\"post\" data-id=\"2108\">m\u00e1quina peletizadora de poliestireno expandido EPE<\/a> produce ruido anormal durante el funcionamiento, m\u00e1s all\u00e1 del rango normal.<\/p>    <h3 class=\"wp-block-heading\">Soluciones<\/h3>    <ul class=\"wp-block-list\"> <li>Verifique las piezas mec\u00e1nicas: verifique las distintas piezas del extrusor de espuma pl\u00e1stica, incluidos cojinetes, dispositivos de transmisi\u00f3n, etc., excluya piezas da\u00f1adas o desgastadas y lubr\u00edquelas o reempl\u00e1celas.<\/li>    <li>Apriete las piezas sueltas: revise los tornillos, tuercas y otras piezas de la espuma pl\u00e1stica extruida para asegurarse de que est\u00e9n bien apretados para minimizar la vibraci\u00f3n mec\u00e1nica causada por el ruido.<\/li>    <li>Mantenimiento del dispositivo reductor de ruido: Compruebe que el dispositivo reductor de ruido est\u00e9 funcionando correctamente y realice la limpieza y mantenimiento necesarios.<\/li> <\/ul>   <div class=\"wp-block-image\"> <figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/09\/EPE-pelletizer-1.webp\" alt=\"peletizadora EPE\" class=\"wp-image-4884\" srcset=\"https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/09\/EPE-pelletizer-1.webp 720w, https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/09\/EPE-pelletizer-1-360x270.webp 360w, https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/09\/EPE-pelletizer-1-240x180.webp 240w, https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/09\/EPE-pelletizer-1-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">peletizadora EPE<\/figcaption><\/figure> <\/div>   <h2 class=\"wp-block-heading\">Desgaste de piezas mec\u00e1nicas.<\/h2>    <p class=\"wp-block-paragraph\">Despu\u00e9s de un largo tiempo de uso, las partes mec\u00e1nicas del extrusor de espuma pl\u00e1stica, como moldes, tornillos, etc., pueden desgastarse, afectando la eficiencia de producci\u00f3n y la calidad del producto.<\/p>    <h3 class=\"wp-block-heading\">Soluciones<\/h3>    <ul class=\"wp-block-list\"> <li>Inspecci\u00f3n y lubricaci\u00f3n peri\u00f3dicas: compruebe peri\u00f3dicamente el desgaste de las piezas mec\u00e1nicas y realice una lubricaci\u00f3n y mantenimiento oportunos para prolongar la vida \u00fatil.<\/li>    <li>Reemplazo de piezas desgastadas: una vez que se encuentre un desgaste grave, reemplace las piezas mec\u00e1nicas da\u00f1adas a tiempo para garantizar el funcionamiento normal de la extrusora de espuma pl\u00e1stica.<\/li> <\/ul>   <div class=\"wp-block-image\"> <figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/11\/EPS-foam-recycling-pelletizing-machine.webp\" alt=\"extrusora de espuma pl\u00e1stica\" class=\"wp-image-3015\" srcset=\"https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/11\/EPS-foam-recycling-pelletizing-machine.webp 720w, https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/11\/EPS-foam-recycling-pelletizing-machine-360x270.webp 360w, https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/11\/EPS-foam-recycling-pelletizing-machine-240x180.webp 240w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">extrusora de espuma pl\u00e1stica<\/figcaption><\/figure> <\/div>","protected":false},"excerpt":{"rendered":"<p>La extrusora de espuma pl\u00e1stica es un equipo com\u00fanmente utilizado para fabricar gr\u00e1nulos de espuma a partir de espuma pl\u00e1stica mediante fusi\u00f3n y extrusi\u00f3n. Sin embargo, en el proceso de uso, varias fallas\u2026<\/p>","protected":false},"author":1,"featured_media":3014,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[43,34],"tags":[],"class_list":["post-3028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-casenews"],"taxonomy_info":{"category":[{"value":43,"label":"News"},{"value":34,"label":"Case&amp;News"}]},"featured_image_src_large":["https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/11\/EPS-foam-pelletizing-machine.webp",720,540,false],"author_info":{"display_name":"Elena","author_link":"https:\/\/plasticrecyclingmachinery.com\/es\/author\/adminmolly\/"},"comment_info":0,"category_info":[{"term_id":43,"name":"News","slug":"news","term_group":0,"term_taxonomy_id":43,"taxonomy":"category","description":"","parent":34,"count":178,"filter":"raw","cat_ID":43,"category_count":178,"category_description":"","cat_name":"News","category_nicename":"news","category_parent":34},{"term_id":34,"name":"Case&amp;News","slug":"casenews","term_group":0,"term_taxonomy_id":34,"taxonomy":"category","description":"","parent":0,"count":234,"filter":"raw","cat_ID":34,"category_count":234,"category_description":"","cat_name":"Case&amp;News","category_nicename":"casenews","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/plasticrecyclingmachinery.com\/es\/wp-json\/wp\/v2\/posts\/3028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plasticrecyclingmachinery.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plasticrecyclingmachinery.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plasticrecyclingmachinery.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/plasticrecyclingmachinery.com\/es\/wp-json\/wp\/v2\/comments?post=3028"}],"version-history":[{"count":0,"href":"https:\/\/plasticrecyclingmachinery.com\/es\/wp-json\/wp\/v2\/posts\/3028\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plasticrecyclingmachinery.com\/es\/wp-json\/wp\/v2\/media\/3014"}],"wp:attachment":[{"href":"https:\/\/plasticrecyclingmachinery.com\/es\/wp-json\/wp\/v2\/media?parent=3028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plasticrecyclingmachinery.com\/es\/wp-json\/wp\/v2\/categories?post=3028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plasticrecyclingmachinery.com\/es\/wp-json\/wp\/v2\/tags?post=3028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}