{"id":3492,"date":"2024-03-04T15:43:19","date_gmt":"2024-03-04T07:43:19","guid":{"rendered":"https:\/\/plasticrecyclingmachinery.com\/?p=3492"},"modified":"2024-03-04T15:43:20","modified_gmt":"2024-03-04T07:43:20","slug":"small-plastic-pelletizer-machine","status":"publish","type":"post","link":"https:\/\/plasticrecyclingmachinery.com\/fr\/small-plastic-pelletizer-machine\/","title":{"rendered":"Pourquoi la petite machine de pelletisation en plastique ne d\u00e9marre-t-elle pas\u00a0?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">La petite machine de granulation du plastique joue un r\u00f4le cl\u00e9 dans le processus de recyclage et de r\u00e9utilisation du plastique. Cependant, nous pouvons parfois \u00eatre confront\u00e9s au probl\u00e8me que la machine de granulation de recyclage du plastique ne peut pas d\u00e9marrer, ce qui affecte non seulement l'efficacit\u00e9 de la production, mais peut \u00e9galement entra\u00eener un gaspillage de ressources. Dans cet article, nous discuterons de quelques raisons courantes pour lesquelles les granulateurs en plastique ne peuvent pas d\u00e9marrer et proposerons des contre-mesures correspondantes.<\/p>   <div class=\"wp-block-image\"> <figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/plastic-scrap-granulator.webp\" alt=\"granulateur de d\u00e9chets plastiques\" class=\"wp-image-2510\" title=\"granulateur de d\u00e9chets plastiques\" srcset=\"https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/plastic-scrap-granulator.webp 720w, https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/plastic-scrap-granulator-360x270.webp 360w, https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/plastic-scrap-granulator-240x180.webp 240w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">granulateur de d\u00e9chets plastiques<\/figcaption><\/figure> <\/div>   <h2 class=\"wp-block-heading\">D\u00e9faillance du syst\u00e8me \u00e9lectrique d'une petite machine \u00e0 pelletiser en plastique<\/h2>    <p class=\"wp-block-paragraph\">Une raison possible pour laquelle une petite machine \u00e0 granuler le plastique ne d\u00e9marre pas est un d\u00e9faut dans le syst\u00e8me \u00e9lectrique. Cela peut inclure des probl\u00e8mes d'alimentation \u00e9lectrique, de mauvaises connexions de c\u00e2bles ou des composants \u00e9lectriques endommag\u00e9s, entra\u00eenant une interruption de la transmission du signal et un d\u00e9marrage incorrect de la machine de granulation de plastique.<\/p>    <h2 class=\"wp-block-heading\">Panne de composant m\u00e9canique<\/h2>    <p class=\"wp-block-paragraph\">Outre le syst\u00e8me \u00e9lectrique, la d\u00e9faillance de composants m\u00e9caniques est une autre raison possible pour laquelle une petite machine \u00e0 granuler le plastique ne d\u00e9marre pas. Par exemple, des dommages aux roulements des composants principaux et des probl\u00e8mes avec le syst\u00e8me de transmission m\u00e9canique affecteront le fonctionnement normal de l'extrudeuse de recyclage du plastique et entraveront le processus de d\u00e9marrage.<\/p>   <div class=\"wp-block-image\"> <figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/plastic-granulator.webp\" alt=\"petite machine de granulation en plastique\" class=\"wp-image-2625\" title=\"petite machine de granulation en plastique\" srcset=\"https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/plastic-granulator.webp 720w, https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/plastic-granulator-360x270.webp 360w, https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/plastic-granulator-240x180.webp 240w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">petite machine de granulation en plastique<\/figcaption><\/figure> <\/div>   <h2 class=\"wp-block-heading\">Probl\u00e8mes avec le syst\u00e8me de lubrification<\/h2>    <p class=\"wp-block-paragraph\">Le syst\u00e8me de lubrification est l\u2019un des facteurs cl\u00e9s affectant le fonctionnement des extrudeuses de recyclage du plastique. S'il y a des probl\u00e8mes avec le syst\u00e8me de lubrification, tels qu'un manque d'huile, des tuyaux de lubrification obstru\u00e9s ou une qualit\u00e9 de lubrifiant non qualifi\u00e9e, cela entra\u00eenera une friction m\u00e9canique accrue, ce qui rendra le processus de d\u00e9marrage difficile, voire impossible.<\/p>    <h2 class=\"wp-block-heading\">Les solutions du pelletiseur en plastique ne d\u00e9marrent pas<\/h2>    <ul class=\"wp-block-list\"> <li>V\u00e9rifiez le syst\u00e8me \u00e9lectrique du<strong><a href=\"https:\/\/plasticrecyclingmachinery.com\/fr\/plastic-extruder-machine\/\" data-type=\"post\" data-id=\"2024\"> petite machine de granulation en plastique <\/a><\/strong>pour vous assurer que les connexions \u00e9lectriques fonctionnent correctement et que les c\u00e2bles ne sont pas endommag\u00e9s ou n'\u00e9tablissent pas de mauvais contacts. V\u00e9rifiez \u00e9galement les fusibles du panneau de commande principal pour vous assurer qu\u2019ils ne sont pas grill\u00e9s. Si des composants \u00e9lectriques sont d\u00e9fectueux, ils doivent \u00eatre r\u00e9par\u00e9s ou remplac\u00e9s par un technicien \u00e9lectricien professionnel.<\/li>    <li>V\u00e9rifiez le syst\u00e8me d'entra\u00eenement principal de la petite machine \u00e0 granuler le plastique, y compris le moteur, les courroies et les engrenages. Assurez-vous qu'ils sont bien connect\u00e9s et qu'ils ne sont pas cass\u00e9s ou endommag\u00e9s. V\u00e9rifiez \u00e9galement que le moteur de l\u2019extrudeuse de recyclage du plastique fonctionne correctement et qu\u2019il n\u2019y a pas de bruits ou d\u2019odeurs inhabituelles. Si des probl\u00e8mes sont d\u00e9tect\u00e9s, le moteur devra peut-\u00eatre \u00eatre r\u00e9par\u00e9 ou remplac\u00e9.<\/li>    <li>V\u00e9rifiez le niveau et la qualit\u00e9 du lubrifiant pour vous assurer qu'il est ad\u00e9quat et non contamin\u00e9. V\u00e9rifiez les tuyaux et les pompes du syst\u00e8me de lubrification pour vous assurer qu'ils ne fuient pas ou ne sont pas obstru\u00e9s. Changez r\u00e9guli\u00e8rement le lubrifiant pour garantir que les pi\u00e8ces m\u00e9caniques restent bien lubrifi\u00e9es pendant le fonctionnement. Si des probl\u00e8mes sont d\u00e9tect\u00e9s avec le syst\u00e8me de lubrification, r\u00e9solvez-les rapidement pour garantir le bon fonctionnement de l'extrudeuse de recyclage du plastique.<\/li> <\/ul>   <div class=\"wp-block-image\"> <figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/plastic-granulation-equipment.webp\" alt=\"\u00e9quipement de granulation de plastique\" class=\"wp-image-2583\" title=\"\u00e9quipement de granulation de plastique\" srcset=\"https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/plastic-granulation-equipment.webp 720w, https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/plastic-granulation-equipment-360x270.webp 360w, https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/plastic-granulation-equipment-240x180.webp 240w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">\u00e9quipement de granulation de plastique<\/figcaption><\/figure> <\/div>","protected":false},"excerpt":{"rendered":"<p>La petite machine de granulation du plastique joue un r\u00f4le cl\u00e9 dans le processus de recyclage et de r\u00e9utilisation du plastique. Cependant, nous pouvons parfois \u00eatre confront\u00e9s au probl\u00e8me du recyclage du plastique\u2026<\/p>","protected":false},"author":1,"featured_media":2509,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[34,43],"tags":[],"class_list":["post-3492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casenews","category-news"],"taxonomy_info":{"category":[{"value":34,"label":"Case&amp;News"},{"value":43,"label":"News"}]},"featured_image_src_large":["https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/plastic-pelletizing-recycling-machine.webp",720,540,false],"author_info":{"display_name":"Elena","author_link":"https:\/\/plasticrecyclingmachinery.com\/fr\/author\/adminmolly\/"},"comment_info":0,"category_info":[{"term_id":34,"name":"Case&amp;News","slug":"casenews","term_group":0,"term_taxonomy_id":34,"taxonomy":"category","description":"","parent":0,"count":234,"filter":"raw","cat_ID":34,"category_count":234,"category_description":"","cat_name":"Case&amp;News","category_nicename":"casenews","category_parent":0},{"term_id":43,"name":"News","slug":"news","term_group":0,"term_taxonomy_id":43,"taxonomy":"category","description":"","parent":34,"count":178,"filter":"raw","cat_ID":43,"category_count":178,"category_description":"","cat_name":"News","category_nicename":"news","category_parent":34}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/plasticrecyclingmachinery.com\/fr\/wp-json\/wp\/v2\/posts\/3492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plasticrecyclingmachinery.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plasticrecyclingmachinery.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plasticrecyclingmachinery.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/plasticrecyclingmachinery.com\/fr\/wp-json\/wp\/v2\/comments?post=3492"}],"version-history":[{"count":0,"href":"https:\/\/plasticrecyclingmachinery.com\/fr\/wp-json\/wp\/v2\/posts\/3492\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plasticrecyclingmachinery.com\/fr\/wp-json\/wp\/v2\/media\/2509"}],"wp:attachment":[{"href":"https:\/\/plasticrecyclingmachinery.com\/fr\/wp-json\/wp\/v2\/media?parent=3492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plasticrecyclingmachinery.com\/fr\/wp-json\/wp\/v2\/categories?post=3492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plasticrecyclingmachinery.com\/fr\/wp-json\/wp\/v2\/tags?post=3492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}