{"id":3349,"date":"2024-01-24T16:34:53","date_gmt":"2024-01-24T08:34:53","guid":{"rendered":"https:\/\/plasticrecyclingmachinery.com\/?p=3349"},"modified":"2024-01-24T16:35:25","modified_gmt":"2024-01-24T08:35:25","slug":"plastic-film-crusher-machine-vibrate","status":"publish","type":"post","link":"https:\/\/plasticrecyclingmachinery.com\/pt\/plastic-film-crusher-machine-vibrate\/","title":{"rendered":"Por que a m\u00e1quina trituradora de filme pl\u00e1stico vibra durante o trabalho?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">A m\u00e1quina trituradora de filme pl\u00e1stico \u00e9 um tipo de equipamento muito utilizado na reciclagem de res\u00edduos pl\u00e1sticos, por\u00e9m, no processo de utiliza\u00e7\u00e3o, alguns usu\u00e1rios podem enfrentar o problema de vibra\u00e7\u00e3o que ocorre de vez em quando quando a m\u00e1quina est\u00e1 funcionando. Neste artigo, discutiremos em profundidade os motivos da vibra\u00e7\u00e3o da m\u00e1quina trituradora de res\u00edduos de pl\u00e1stico em opera\u00e7\u00e3o e proporemos algumas solu\u00e7\u00f5es para garantir o bom funcionamento da m\u00e1quina.<\/p>   <div class=\"wp-block-image\"> <figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/water-bottle-crusher.webp\" alt=\"m\u00e1quina trituradora de filme pl\u00e1stico\" class=\"wp-image-2571\" title=\"m\u00e1quina trituradora de filme pl\u00e1stico\" srcset=\"https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/water-bottle-crusher.webp 720w, https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/water-bottle-crusher-360x270.webp 360w, https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/water-bottle-crusher-240x180.webp 240w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">m\u00e1quina trituradora de filme pl\u00e1stico<\/figcaption><\/figure> <\/div>   <h2 class=\"wp-block-heading\">Raz\u00f5es para a vibra\u00e7\u00e3o da m\u00e1quina trituradora de filme pl\u00e1stico<\/h2>    <h3 class=\"wp-block-heading\">Desgaste irregular de facas<\/h3>    <p class=\"wp-block-paragraph\">As facas s\u00e3o os principais componentes da m\u00e1quina trituradora de filme pl\u00e1stico. Se as facas se desgastarem de maneira irregular, a m\u00e1quina vibrar\u00e1 durante a opera\u00e7\u00e3o. O desgaste da faca \u00e9 inevit\u00e1vel ap\u00f3s uso prolongado, mas a falha em substitu\u00ed-la ou mant\u00ea-la a tempo pode levar ao aumento de problemas de vibra\u00e7\u00e3o.<\/p>    <h3 class=\"wp-block-heading\">Falha no rolamento<\/h3>    <p class=\"wp-block-paragraph\">Os rolamentos dentro da m\u00e1quina trituradora de filme pl\u00e1stico s\u00e3o respons\u00e1veis \u200b\u200bpor apoiar as pe\u00e7as rotativas. Se os rolamentos falharem, isso causar\u00e1 instabilidade e vibra\u00e7\u00e3o quando a m\u00e1quina estiver funcionando. Problemas nos rolamentos podem ser causados \u200b\u200bpor uso prolongado, lubrifica\u00e7\u00e3o insuficiente ou entrada de contaminantes.<\/p>   <div class=\"wp-block-image\"> <figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/11\/plastic-waste-shredder-machine.webp\" alt=\"triturador de materiais pl\u00e1sticos\" class=\"wp-image-2882\" title=\"triturador de materiais pl\u00e1sticos\" srcset=\"https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/11\/plastic-waste-shredder-machine.webp 720w, https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/11\/plastic-waste-shredder-machine-360x270.webp 360w, https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/11\/plastic-waste-shredder-machine-240x180.webp 240w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">triturador de materiais pl\u00e1sticos <\/figcaption><\/figure> <\/div>   <h3 class=\"wp-block-heading\">Alimenta\u00e7\u00e3o irregular<\/h3>    <p class=\"wp-block-paragraph\">Durante o processo de britagem do pl\u00e1stico, se o avan\u00e7o n\u00e3o for uniforme, pode causar um desequil\u00edbrio de carga na m\u00e1quina, podendo causar vibra\u00e7\u00e3o. Isso pode estar relacionado ao formato e tamanho do material ou \u00e0 forma como ele \u00e9 alimentado.<\/p>    <h3 class=\"wp-block-heading\">Problemas motores<\/h3>    <p class=\"wp-block-paragraph\">O motor \u00e9 a fonte de energia da m\u00e1quina trituradora de filme pl\u00e1stico, se houver problemas com o motor, como curto-circuito dos enrolamentos, entortamento do eixo do motor, etc., isso causar\u00e1 vibra\u00e7\u00e3o da m\u00e1quina durante a opera\u00e7\u00e3o.<\/p>    <h2 class=\"wp-block-heading\">Maneiras de resolver a vibra\u00e7\u00e3o do triturador de pl\u00e1stico<\/h2>    <h3 class=\"wp-block-heading\">Inspe\u00e7\u00e3o regular e substitui\u00e7\u00e3o de facas<\/h3>    <p class=\"wp-block-paragraph\">Para evitar o desgaste irregular das facas, o operador deve verificar regularmente o desgaste das l\u00e2minas da m\u00e1quina trituradora de pl\u00e1stico e substituir imediatamente as facas muito desgastadas. Manter a nitidez dos cortadores ajudar\u00e1 a reduzir a vibra\u00e7\u00e3o da m\u00e1quina durante a opera\u00e7\u00e3o e prolongar\u00e1 a vida \u00fatil da m\u00e1quina trituradora de res\u00edduos de pl\u00e1stico.<\/p>    <h3 class=\"wp-block-heading\">Lubrifica\u00e7\u00e3o regular dos rolamentos<\/h3>    <p class=\"wp-block-paragraph\">Lubrifique e fa\u00e7a manuten\u00e7\u00e3o regularmente nos rolamentos da m\u00e1quina trituradora de filme pl\u00e1stico para garantir que estejam em boas condi\u00e7\u00f5es de funcionamento. Lubrificante adequado e substitui\u00e7\u00e3o regular s\u00e3o meios eficazes para evitar falhas nos rolamentos.<\/p>   <div class=\"wp-block-image\"> <figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/water-bottle-crusher-machine.webp\" alt=\"triturador de res\u00edduos de pl\u00e1stico\" class=\"wp-image-2589\" title=\"triturador de res\u00edduos de pl\u00e1stico\" srcset=\"https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/water-bottle-crusher-machine.webp 720w, https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/water-bottle-crusher-machine-360x270.webp 360w, https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/water-bottle-crusher-machine-240x180.webp 240w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">triturador de res\u00edduos de pl\u00e1stico<\/figcaption><\/figure> <\/div>   <h3 class=\"wp-block-heading\">Controle o feed uniformemente<\/h3>    <p class=\"wp-block-paragraph\">Ao ajustar o m\u00e9todo de alimenta\u00e7\u00e3o, certifique-se de que o material possa ser distribu\u00eddo uniformemente na fresa para evitar a instabilidade da m\u00e1quina causada pela alimenta\u00e7\u00e3o irregular. Considere usar um dispositivo de alimenta\u00e7\u00e3o para obter uma alimenta\u00e7\u00e3o mais uniforme.<\/p>    <h3 class=\"wp-block-heading\">Verifica\u00e7\u00f5es regulares do motor<\/h3>    <p class=\"wp-block-paragraph translation-block\">Verifique regularmente o estado de funcionamento do motor da m\u00e1quina trituradora de pl\u00e1stico recicl\u00e1vel, incluindo o enrolamento do motor, a curvatura do eixo e outras condi\u00e7\u00f5es. Encontre problemas a tempo e repare ou substitua-os para garantir o funcionamento normal do motor e reduzir a vibra\u00e7\u00e3o da <strong><a href=\"https:\/\/plasticrecyclingmachinery.com\/pt\/plastic-film-shredder\/\" data-type=\"post\" data-id=\"2414\">m\u00e1quina trituradora de pl\u00e1stico recicl\u00e1vel<\/a><\/strong>.<\/p>   <div class=\"wp-block-image\"> <figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/11\/plastic-materials-shredder.webp\" alt=\"f\u00e1brica de m\u00e1quinas trituradoras de pl\u00e1stico\" class=\"wp-image-2999\" title=\"f\u00e1brica de m\u00e1quinas trituradoras de pl\u00e1stico\" srcset=\"https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/11\/plastic-materials-shredder.webp 720w, https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/11\/plastic-materials-shredder-360x270.webp 360w, https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/11\/plastic-materials-shredder-240x180.webp 240w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">f\u00e1brica de m\u00e1quinas trituradoras de pl\u00e1stico <\/figcaption><\/figure> <\/div>","protected":false},"excerpt":{"rendered":"<p>A m\u00e1quina trituradora de filme pl\u00e1stico \u00e9 um tipo de equipamento muito utilizado na reciclagem de res\u00edduos pl\u00e1sticos, por\u00e9m, no processo de utiliza\u00e7\u00e3o, alguns usu\u00e1rios podem\u2026<\/p>","protected":false},"author":1,"featured_media":2573,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[43,34],"tags":[],"class_list":["post-3349","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-casenews"],"taxonomy_info":{"category":[{"value":43,"label":"News"},{"value":34,"label":"Case&amp;News"}]},"featured_image_src_large":["https:\/\/plasticrecyclingmachinery.com\/wp-content\/uploads\/2023\/10\/plastic-shredder-machine-for-sale.webp",720,540,false],"author_info":{"display_name":"Elena","author_link":"https:\/\/plasticrecyclingmachinery.com\/pt\/author\/adminmolly\/"},"comment_info":0,"category_info":[{"term_id":43,"name":"News","slug":"news","term_group":0,"term_taxonomy_id":43,"taxonomy":"category","description":"","parent":34,"count":178,"filter":"raw","cat_ID":43,"category_count":178,"category_description":"","cat_name":"News","category_nicename":"news","category_parent":34},{"term_id":34,"name":"Case&amp;News","slug":"casenews","term_group":0,"term_taxonomy_id":34,"taxonomy":"category","description":"","parent":0,"count":234,"filter":"raw","cat_ID":34,"category_count":234,"category_description":"","cat_name":"Case&amp;News","category_nicename":"casenews","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/plasticrecyclingmachinery.com\/pt\/wp-json\/wp\/v2\/posts\/3349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plasticrecyclingmachinery.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plasticrecyclingmachinery.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plasticrecyclingmachinery.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/plasticrecyclingmachinery.com\/pt\/wp-json\/wp\/v2\/comments?post=3349"}],"version-history":[{"count":0,"href":"https:\/\/plasticrecyclingmachinery.com\/pt\/wp-json\/wp\/v2\/posts\/3349\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plasticrecyclingmachinery.com\/pt\/wp-json\/wp\/v2\/media\/2573"}],"wp:attachment":[{"href":"https:\/\/plasticrecyclingmachinery.com\/pt\/wp-json\/wp\/v2\/media?parent=3349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plasticrecyclingmachinery.com\/pt\/wp-json\/wp\/v2\/categories?post=3349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plasticrecyclingmachinery.com\/pt\/wp-json\/wp\/v2\/tags?post=3349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}